{"id":30312,"date":"2026-06-13T11:40:50","date_gmt":"2026-06-13T08:40:50","guid":{"rendered":"https:\/\/dognrose.com\/?post_type=product&#038;p=30312"},"modified":"2026-06-13T11:46:24","modified_gmt":"2026-06-13T08:46:24","slug":"skateboard-cafe-omar-odom-henry-deck","status":"publish","type":"product","link":"https:\/\/dognrose.com\/en\/product\/skateboard-cafe-omar-odom-henry-deck\/","title":{"rendered":"SKATEBOARD CAFE &#8211; OMAR ODOM HENRY DECK"},"content":{"rendered":"<p>FREE GRIP INCLUDED<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FREE GRIP INCLUDED<\/p>\n","protected":false},"featured_media":30316,"template":"","meta":[],"product_brand":[],"product_cat":[294,114],"product_tag":[],"class_list":["post-30312","product","type-product","status-publish","has-post-thumbnail","product_cat-skateboard-cafe","product_cat-decks-2","first","instock","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SKATEBOARD CAFE - OMAR ODOM HENRY DECK - Dognrose<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SKATEBOARD CAFE - OMAR ODOM HENRY DECK - Dognrose\" \/>\n<meta property=\"og:description\" content=\"FREE GRIP INCLUDED\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/\" \/>\n<meta property=\"og:site_name\" content=\"Dognrose\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-13T08:46:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dognrose.com\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-13-114554.png\" \/>\n\t<meta property=\"og:image:width\" content=\"608\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/product\\\/skateboard-cafe-omar-odom-henry-deck\\\/\",\"url\":\"https:\\\/\\\/dognrose.com\\\/product\\\/skateboard-cafe-omar-odom-henry-deck\\\/\",\"name\":\"SKATEBOARD CAFE - OMAR ODOM HENRY DECK - Dognrose\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/product\\\/skateboard-cafe-omar-odom-henry-deck\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/product\\\/skateboard-cafe-omar-odom-henry-deck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dognrose.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2026-06-13-114554.png\",\"datePublished\":\"2026-06-13T08:40:50+00:00\",\"dateModified\":\"2026-06-13T08:46:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/product\\\/skateboard-cafe-omar-odom-henry-deck\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dognrose.com\\\/product\\\/skateboard-cafe-omar-odom-henry-deck\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/product\\\/skateboard-cafe-omar-odom-henry-deck\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dognrose.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2026-06-13-114554.png\",\"contentUrl\":\"https:\\\/\\\/dognrose.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2026-06-13-114554.png\",\"width\":608,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/product\\\/skateboard-cafe-omar-odom-henry-deck\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/dognrose.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dognrose.com\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SKATEBOARD CAFE &#8211; OMAR ODOM HENRY DECK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/#website\",\"url\":\"https:\\\/\\\/dognrose.com\\\/\",\"name\":\"Dognrose\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dognrose.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/#organization\",\"name\":\"Dognrose\",\"url\":\"https:\\\/\\\/dognrose.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dognrose.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-tBmlWvQIlg-dognrose-logo-bandw-png-scaled-1.webp\",\"contentUrl\":\"https:\\\/\\\/dognrose.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-tBmlWvQIlg-dognrose-logo-bandw-png-scaled-1.webp\",\"width\":2560,\"height\":548,\"caption\":\"Dognrose\"},\"image\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SKATEBOARD CAFE - OMAR ODOM HENRY DECK - Dognrose","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/","og_locale":"en_US","og_type":"article","og_title":"SKATEBOARD CAFE - OMAR ODOM HENRY DECK - Dognrose","og_description":"FREE GRIP INCLUDED","og_url":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/","og_site_name":"Dognrose","article_modified_time":"2026-06-13T08:46:24+00:00","og_image":[{"width":608,"height":485,"url":"http:\/\/dognrose.com\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-13-114554.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/","url":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/","name":"SKATEBOARD CAFE - OMAR ODOM HENRY DECK - Dognrose","isPartOf":{"@id":"https:\/\/dognrose.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/#primaryimage"},"image":{"@id":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/#primaryimage"},"thumbnailUrl":"https:\/\/dognrose.com\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-13-114554.png","datePublished":"2026-06-13T08:40:50+00:00","dateModified":"2026-06-13T08:46:24+00:00","breadcrumb":{"@id":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/#primaryimage","url":"https:\/\/dognrose.com\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-13-114554.png","contentUrl":"https:\/\/dognrose.com\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-13-114554.png","width":608,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/dognrose.com\/product\/skateboard-cafe-omar-odom-henry-deck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/dognrose.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dognrose.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"SKATEBOARD CAFE &#8211; OMAR ODOM HENRY DECK"}]},{"@type":"WebSite","@id":"https:\/\/dognrose.com\/#website","url":"https:\/\/dognrose.com\/","name":"Dognrose","description":"","publisher":{"@id":"https:\/\/dognrose.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dognrose.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dognrose.com\/#organization","name":"Dognrose","url":"https:\/\/dognrose.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dognrose.com\/#\/schema\/logo\/image\/","url":"https:\/\/dognrose.com\/wp-content\/uploads\/2023\/07\/cropped-tBmlWvQIlg-dognrose-logo-bandw-png-scaled-1.webp","contentUrl":"https:\/\/dognrose.com\/wp-content\/uploads\/2023\/07\/cropped-tBmlWvQIlg-dognrose-logo-bandw-png-scaled-1.webp","width":2560,"height":548,"caption":"Dognrose"},"image":{"@id":"https:\/\/dognrose.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/product\/30312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/media\/30316"}],"wp:attachment":[{"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/media?parent=30312"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/product_brand?post=30312"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/product_cat?post=30312"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/product_tag?post=30312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}