{"id":262,"count":14,"description":"","link":"https:\/\/dognrose.com\/en\/product-category\/magenta-en\/","name":"MAGENTA","slug":"magenta-en","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MAGENTA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dognrose.com\/product-category\/magenta\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAGENTA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dognrose.com\/product-category\/magenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Dognrose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/product-category\\\/magenta\\\/\",\"url\":\"https:\\\/\\\/dognrose.com\\\/product-category\\\/magenta\\\/\",\"name\":\"MAGENTA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/product-category\\\/magenta\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/product-category\\\/magenta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/dognrose.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MAGENTA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/#website\",\"url\":\"https:\\\/\\\/dognrose.com\\\/\",\"name\":\"Dognrose\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dognrose.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/#organization\",\"name\":\"Dognrose\",\"url\":\"https:\\\/\\\/dognrose.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dognrose.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dognrose.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-tBmlWvQIlg-dognrose-logo-bandw-png-scaled-1.webp\",\"contentUrl\":\"https:\\\/\\\/dognrose.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-tBmlWvQIlg-dognrose-logo-bandw-png-scaled-1.webp\",\"width\":2560,\"height\":548,\"caption\":\"Dognrose\"},\"image\":{\"@id\":\"https:\\\/\\\/dognrose.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGENTA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dognrose.com\/product-category\/magenta\/","og_locale":"en_US","og_type":"article","og_title":"MAGENTA","og_url":"https:\/\/dognrose.com\/product-category\/magenta\/","og_site_name":"Dognrose","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dognrose.com\/product-category\/magenta\/","url":"https:\/\/dognrose.com\/product-category\/magenta\/","name":"MAGENTA","isPartOf":{"@id":"https:\/\/dognrose.com\/#website"},"breadcrumb":{"@id":"https:\/\/dognrose.com\/product-category\/magenta\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/dognrose.com\/product-category\/magenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/dognrose.com\/en\/"},{"@type":"ListItem","position":2,"name":"MAGENTA"}]},{"@type":"WebSite","@id":"https:\/\/dognrose.com\/#website","url":"https:\/\/dognrose.com\/","name":"Dognrose","description":"","publisher":{"@id":"https:\/\/dognrose.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dognrose.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dognrose.com\/#organization","name":"Dognrose","url":"https:\/\/dognrose.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dognrose.com\/#\/schema\/logo\/image\/","url":"https:\/\/dognrose.com\/wp-content\/uploads\/2023\/07\/cropped-tBmlWvQIlg-dognrose-logo-bandw-png-scaled-1.webp","contentUrl":"https:\/\/dognrose.com\/wp-content\/uploads\/2023\/07\/cropped-tBmlWvQIlg-dognrose-logo-bandw-png-scaled-1.webp","width":2560,"height":548,"caption":"Dognrose"},"image":{"@id":"https:\/\/dognrose.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/product_cat\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/dognrose.com\/en\/wp-json\/wp\/v2\/product?product_cat=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}